{"id":7682,"date":"2020-07-14T14:10:02","date_gmt":"2020-07-14T14:10:02","guid":{"rendered":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/"},"modified":"2026-04-29T10:56:17","modified_gmt":"2026-04-29T08:56:17","slug":"event-planning","status":"publish","type":"page","link":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/","title":{"rendered":"Event planning"},"content":{"rendered":"\n<div class=\"wp-block-eguma-hero-header c-hero-wrapper\"><div class=\"c-hero-header\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/04\/eguma_referenzen_messe.jpg\" srcset=\"https:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=100&amp;s=93edb7d1a09885981fe45e13f026b29b 100w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=116&amp;s=e43e86560f1866150785462777c07979 116w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=134&amp;s=78712071b38e6bda6b11da75cf560834 134w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=156&amp;s=1d39c9011b6852f5c29589d027b9c4f8 156w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=182&amp;s=eb8b2046d9942ccde496319988c16a13 182w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=210&amp;s=f6d4f342322aa44f9c3f5055987d2669 210w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=244&amp;s=1e459e94cd02234d50147d78adfb3b34 244w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=282&amp;s=9371403748c511a4d6cab320d5c09ac1 282w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=328&amp;s=6540f05fb870cb2412fb70e7b79bd99a 328w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=380&amp;s=a623aacf90d71563446634fe0013858e 380w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=442&amp;s=11d816445f4efdbb5f2b4a70e0c17b9d 442w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=512&amp;s=593f3e9e94c8e19f1824e8cd57d04c90 512w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=594&amp;s=09b75645b810340f27be109c7c60ee37 594w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=688&amp;s=4d511b0e0cb581167ed7eb13f4110172 688w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=798&amp;s=735cbd1d8707e6a9ece59d388530a85b 798w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=926&amp;s=78537fb6d8039252c82a916d032dc140 926w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=1074&amp;s=53f525d06704617185f552947075b76e 1074w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=1246&amp;s=b46699e827abf847371bc7d4d3f2707d 1246w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=1446&amp;s=d18efb4416b1c74d4a55a3a7a6a6d105 1446w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=1678&amp;s=92e7670e5e35c7bc7431bf56b4d4ffa3 1678w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=1946&amp;s=e3c9a37ab2cd9e096295c3529728f824 1946w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=2258&amp;s=761fcde2ed32f92d67d28951cfcdfa7f 2258w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=2618&amp;s=5a4636b23e25aecbee71d43be65f3468 2618w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=3038&amp;s=24e10c7433ab8d947ccd25f2d6128009 3038w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=3524&amp;s=d71c480d4ac783d5eb3c3abeef3cb09c 3524w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=4088&amp;s=5c00b8db978b34c3718ddcfc25d2515c 4088w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=4742&amp;s=46a23ca44269441c9c5a4cd15191e707 4742w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=5500&amp;s=9063bf2acd9314d4e3a271093e5b2409 5500w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=6380&amp;s=a929fce7d37f2710396e4ce8e0868eea 6380w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=7400&amp;s=751664727e19e19fe9f39b72d0c60888 7400w,\nhttps:\/\/eguma-wp.imgix.net\/https%3A%2F%2Fwww.e-guma.ch%2Fen%2Fwp-content%2Fuploads%2F2020%2F04%2Feguma_referenzen_messe.jpg?ixlib=js-2.3.2&amp;auto=format&amp;w=8192&amp;s=07a30b2f90d1f6da82c007573f9216c6 8192w\" sizes=\"100vw\"\/><div class=\"c-hero-header__overlay\">\n<div class=\"m-richtext align--center\"><div class=\"l-constrainer\"><div class=\"c-richtext\">\n<h1 class=\"wp-block-heading\">References Event planning<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">When every ticket counts<\/h2>\n\n\n\n<p>Here, we present a selection of our trade fair, theatre, concert, festival, seminar, award ceremony and sporting event customers.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"m-btn align--left\"><div class=\"l-constrainer\">\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/hotel-industry\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--primary\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Hotel industry<\/span><div class=\"focus-blob\"><\/div><\/a>\n\n\n\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/gastronomy\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--primary\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Gastronomy<\/span><div class=\"focus-blob\"><\/div><\/a>\n\n\n\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/rail-shipping\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--primary\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Rail &amp; Shipping<\/span><div class=\"focus-blob\"><\/div><\/a>\n\n\n\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/tourism-cooperatives\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--primary\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Tourism &amp; Cooperatives<\/span><div class=\"focus-blob\"><\/div><\/a>\n\n\n\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/leisure\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--primary\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Leisure<\/span><div class=\"focus-blob\"><\/div><\/a>\n\n\n\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/spa-beauty\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--primary\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Spa &amp; Beauty<\/span><div class=\"focus-blob\"><\/div><\/a>\n\n\n\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/specialist-retail\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--primary\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Specialist retail<\/span><div class=\"focus-blob\"><\/div><\/a>\n\n\n\n<a href=\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/\" target=\"_self\" class=\"c-btn c-btn--small c-btn--third\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\">Event planning<\/span><div class=\"focus-blob\"><\/div><\/a>\n<\/div><\/div>\n\n\n\n<section class=\"m-ref m-ref--large no-title no-topspace\" data-module=\"ref\"><div class=\"l-constrainer\"><div class=\"ref-grid\">\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.theater-uri.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13215 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2024\/09\/e-guma_referenzen_logo_theater-uri.jpg\" width=\"784\" height=\"441\" alt=\"\" title=\"e-guma_referenzen_logo_theater-uri\" srcset=\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2024\/09\/e-guma_referenzen_logo_theater-uri.jpg 784w, https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2024\/09\/e-guma_referenzen_logo_theater-uri-300x169.jpg 300w, https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2024\/09\/e-guma_referenzen_logo_theater-uri-768x432.jpg 768w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Theater Uri<\/h5><p class=\"c-ref__dest\">Altdorf<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2024\/09\/Kundengeschichten_Theater-Uri_EN.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--handshake\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-handshake\"><\/use><\/svg><span class=\"link__lbl\">Customer story<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/theater-uri\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/theater-uri\/de\/gutscheine\/37296\/wertgutschein\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n<\/div><\/div><\/div><div class=\"c-ref__img\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13216 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2024\/09\/e-guma_referenzen_theater-uri.jpg\" width=\"306\" height=\"392\" alt=\"\" title=\"e-guma_referenzen_theater-uri\" srcset=\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2024\/09\/e-guma_referenzen_theater-uri.jpg 306w, https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2024\/09\/e-guma_referenzen_theater-uri-234x300.jpg 234w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.wigra.com\/de\/home\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4407 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/04\/e-guma_referenzen_logo_wzs.jpg\" width=\"784\" height=\"441\" alt=\"\" title=\"e-guma_referenzen_logo_wzs\" srcset=\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/e-guma_referenzen_logo_wzs.jpg 784w, https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/e-guma_referenzen_logo_wzs-300x169.jpg 300w, https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/e-guma_referenzen_logo_wzs-768x432.jpg 768w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">WZS Management AG<\/h5><p class=\"c-ref__dest\">Cham<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/11\/Kundengeschichte_WZS_EN-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--handshake\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-handshake\"><\/use><\/svg><span class=\"link__lbl\">Customer story<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/wzs-management\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><div class=\"c-ref__img\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4411 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/04\/e-guma_referenzen_wzs.jpg\" width=\"306\" height=\"392\" alt=\"\" title=\"e-guma_referenzen_wzs\" srcset=\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/e-guma_referenzen_wzs.jpg 306w, https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/e-guma_referenzen_wzs-234x300.jpg 234w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/div><\/div><\/div>\n<\/div><\/div><\/section>\n\n\n\n<section class=\"m-ref no-title no-topspace\" data-module=\"ref\"><div class=\"l-constrainer\"><div class=\"ref-grid\">\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.hospitality-summit.ch\/home\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12195 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2021\/08\/e-guma_referenzen_logo_hospitalitysummit.png\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_hospitalitysummit\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Hospitality Summit<\/h5><p class=\"c-ref__dest\">Zurich<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/hospitality-summit\/en\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.htr-milestone.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5270 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_milestone.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_milestone\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">htr hotel revue MILESTONE<\/h5><p class=\"c-ref__dest\">Bern<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/hotelleriesuisse\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.mugg.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13119 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2024\/08\/e-guma_referenzen_zirkus_mugg_logo.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_zirkus_mugg_logo\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Zirkus Mugg<\/h5><p class=\"c-ref__dest\">Betschwanden<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/zirkusmugg\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.musical.ch\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5251 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_showtickets.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_showtickets\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">show tickets ag<\/h5><p class=\"c-ref__dest\">Zurich<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/musical.ch\/en\/gift-vouchers\/20996\/value-voucher\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/musical.ch\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.klippswasserwelt.de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5253 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_klippswasserwelt.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_klippswasserwelt\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Klipp&#8217;s Wasserwelt Catering<\/h5><p class=\"c-ref__dest\">Klipphausen<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/klippswasserwelt\/de\/gutscheine\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/klippswasserwelt\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.freilichtspiele-luzern.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12361 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2022\/05\/e-guma_referenzen_logo_freilichtspielelu.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_freilichtspielelu\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Freilichtspiele Luzern<\/h5><p class=\"c-ref__dest\">Lucerne<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/diewaldstaetter\/de\/gutscheine\/39110\/wertgutschein\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/diewaldstaetter\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.zurichconventioncenter.com\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12362 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2022\/05\/e-guma_referenzen_logo_kongresshauszh.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_kongresshauszh\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Zurich Convention Center<\/h5><p class=\"c-ref__dest\">Zurich<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/kongresshaus-zuerich\/en\/gift-vouchers\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/kongresshaus-zuerich\/en\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--ticket\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-ticket\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"http:\/\/www.glarnermesse.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5261 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_glarnermesse.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_glarnermesse\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Glarner Messe<\/h5><p class=\"c-ref__dest\">N\u00e4fels<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/wzs-management\/de\/tickets\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--ticket\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-ticket\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop admissions<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"http:\/\/www.ama.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5264 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_ama.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_ama\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">AMA Messe<\/h5><p class=\"c-ref__dest\">Aarau<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/wzs-management\/de\/tickets\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--ticket\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-ticket\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop admissions<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/politforumthun.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5266 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_politforumthun.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_politforumthun\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Politforum Thun<\/h5><p class=\"c-ref__dest\">Bern<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/politforum-thun\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/vdh.swiss\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5286 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_vdh.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_vdh\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">VDH &#8211; Vereinigung diplomierter Hoteliers und Restaurateure<\/h5><p class=\"c-ref__dest\">Adliswil<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/vereinigung-diplomierter-hoteliers-vdh\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.hotelgastrounion.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5290 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_hotelgastrounion.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_hotelgastrounion\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Hotel &#038; Gastro Union<\/h5><p class=\"c-ref__dest\">Lucerne<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/hotel-gastro-union\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.freilichtspiel-nw.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5292 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_theatergesellschaft_dallenwil.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_theatergesellschaft_dallenwil\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Freilichtspiel Nidwalden<\/h5><p class=\"c-ref__dest\">Dallenwil<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/theater-dallenwil\/de\/gutscheine\/30312\/wertgutschein-fuer-das-freilichtspiel-2020\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/theater-dallenwil\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.theater-wolfenschiessen.ch\/start\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11722 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2021\/01\/e-guma_referenzen_logo_theaterwolfenschiessen.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_theaterwolfenschiessen\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Theatergesellschaft Wolfenschiessen<\/h5><p class=\"c-ref__dest\">Wolfenschiessen<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/theater-wolfenschiessen\/de\/gutscheine\/33561\/wertgutschein\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/theater-wolfenschiessen\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"http:\/\/www.schule-nuerensdorf.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11721 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2021\/01\/e-guma_referenzen_logo_nuerensdorf.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_nuerensdorf\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Community of N\u00fcrensdorf<\/h5><p class=\"c-ref__dest\">N\u00fcrensdorf<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/freizeitkurse-nuerensdorf\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.bodmer-ton.ch\/en-us\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11720 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2021\/01\/e-guma_referenzen_logo_bodmerton.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_bodmerton\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Bodmer Ton AG<\/h5><p class=\"c-ref__dest\">Einsiedeln<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/bodmer-ton\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/die-planer.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11719 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2021\/01\/e-guma_referenzen_logo_dieplaner_de.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_dieplaner_de\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Die Planer<\/h5><p class=\"c-ref__dest\">Urtenen-Sch\u00f6nb\u00fchl<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/die-planer\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"http:\/\/www.fuerdaskind.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5300 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2020\/05\/e-guma_referenzen_logo_stsiftungfuerdaskind.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_stsiftungfuerdaskind\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Stiftung. F\u00fcr das Kind. Giedion Risch<\/h5><p class=\"c-ref__dest\">Zurich<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/fuerdaskind\/de\/events\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"www.ludotrail.ch\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12379 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2022\/05\/e-guma_referenzen_logo_ludotrail.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_ludotrail\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Ludotrail<\/h5><p class=\"c-ref__dest\">Langnau i. E.<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/ludotrail\/de\/gutscheine\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--giftbox\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-giftbox\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/ludotrail\/de\/tickets\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--ticket\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-ticket\"><\/use><\/svg><span class=\"link__lbl\">Ticket shop admissions<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"ref-grid__box\" class=\"wp-block-eguma-reference\"><div class=\"c-ref\"><div class=\"c-ref__content\"><div class=\"c-ref__logo\"><a class=\"c-ref__logowrap\" href=\"https:\/\/www.antonia.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12811 size-full\" src=\"https:\/\/www.e-guma.ch\/en\/wp-content\/uploads\/2023\/09\/e-guma_referenzen_logo_die-sizilianerin.jpg\" width=\"292\" height=\"179\" alt=\"\" title=\"e-guma_referenzen_logo_die-sizilianerin\"\/><\/a><\/div><div class=\"c-ref__main\"><h5 class=\"c-ref__title\">Die Sizilianerin<\/h5><p class=\"c-ref__dest\">Augsburg<\/p><div class=\"c-ref__linkbox\">\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/diesizilianerin\/de\/gutscheine\" target=\"_blank\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Voucher shop<\/span><\/a>\n\n\n<a class=\"c-link c-link--icon\" href=\"https:\/\/shop.e-guma.ch\/diesizilianerin\/de\/events\" rel=\"noopener noreferrer\"><svg class=\"c-icon c-icon--16 c-icon--calendar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-calendar\"><\/use><\/svg><span class=\"link__lbl\">Ticket Shop events<\/span><\/a>\n\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/section>\n\n\n\n<section class=\"m-teaserstage l-full\"><div class=\"l-constrainer\"><div class=\"bg\"><\/div><div class=\"stage-wrapper\">\n<div class=\"m-article align--center\" data-module=\"article\"><div class=\"l-constrainer\">\n<div class=\"m-richtext align--center\"><div class=\"l-constrainer\"><div class=\"c-richtext\">\n<h2 class=\"wp-block-heading has-text-align-center\"><br>Would you like to learn more?<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Request a non-binding consultation.<br>We look forward to your call or message.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"m-btn align--center\"><div class=\"l-constrainer\">\n<a href=\"https:\/\/www.e-guma.ch\/en\/make-an-appointment\/\" target=\"_self\" class=\"c-btn c-btn--default c-btn--invert c-btn--icon-lbl\" rel=\"noopener noreferrer\" data-module=\"button\"><span class=\"btn-label\"><svg class=\"c-icon c-icon--16 c-icon--avatar\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 190 190\"><use href=\"\/wp-content\/themes\/eguma-template\/frontend\/dist\/assets\/images\/svg-sprite.svg#sprite-avatar\"><\/use><\/svg>Request a consultation<\/span><div class=\"focus-blob\"><\/div><\/a>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":4470,"parent":7632,"menu_order":39,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7682","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Event planning - e-guma | Voucher System and Ticketing System<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Event planning - e-guma | Voucher System and Ticketing System\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/\" \/>\n<meta property=\"og:site_name\" content=\"e-guma | Voucher System and Ticketing System\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T08:56:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"947\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/\",\"url\":\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/\",\"name\":\"Event planning - e-guma | Voucher System and Ticketing System\",\"isPartOf\":{\"@id\":\"https:\/\/www.e-guma.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg\",\"datePublished\":\"2020-07-14T14:10:02+00:00\",\"dateModified\":\"2026-04-29T08:56:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#primaryimage\",\"url\":\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg\",\"contentUrl\":\"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg\",\"width\":2000,\"height\":947,\"caption\":\"e-guma references event planning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.e-guma.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\/\/www.e-guma.ch\/en\/references\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Event planning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.e-guma.ch\/en\/#website\",\"url\":\"https:\/\/www.e-guma.ch\/en\/\",\"name\":\"e-guma | Voucher System and Ticketing System\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.e-guma.ch\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Event planning - e-guma | Voucher System and Ticketing System","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/","og_locale":"en_US","og_type":"article","og_title":"Event planning - e-guma | Voucher System and Ticketing System","og_url":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/","og_site_name":"e-guma | Voucher System and Ticketing System","article_modified_time":"2026-04-29T08:56:17+00:00","og_image":[{"width":2000,"height":947,"url":"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/","url":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/","name":"Event planning - e-guma | Voucher System and Ticketing System","isPartOf":{"@id":"https:\/\/www.e-guma.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#primaryimage"},"image":{"@id":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#primaryimage"},"thumbnailUrl":"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg","datePublished":"2020-07-14T14:10:02+00:00","dateModified":"2026-04-29T08:56:17+00:00","breadcrumb":{"@id":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-guma.ch\/en\/references\/event-planning\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#primaryimage","url":"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg","contentUrl":"https:\/\/eguma-wordpress.s3.amazonaws.com\/en\/uploads\/2020\/04\/eguma_referenzen_messe.jpg","width":2000,"height":947,"caption":"e-guma references event planning"},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-guma.ch\/en\/references\/event-planning\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.e-guma.ch\/en\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/www.e-guma.ch\/en\/references\/"},{"@type":"ListItem","position":3,"name":"Event planning"}]},{"@type":"WebSite","@id":"https:\/\/www.e-guma.ch\/en\/#website","url":"https:\/\/www.e-guma.ch\/en\/","name":"e-guma | Voucher System and Ticketing System","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-guma.ch\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/pages\/7682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/comments?post=7682"}],"version-history":[{"count":43,"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/pages\/7682\/revisions"}],"predecessor-version":[{"id":14252,"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/pages\/7682\/revisions\/14252"}],"up":[{"embeddable":true,"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/pages\/7632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/media\/4470"}],"wp:attachment":[{"href":"https:\/\/www.e-guma.ch\/en\/wp-json\/wp\/v2\/media?parent=7682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}